{"id":684513,"date":"2026-03-27T16:19:51","date_gmt":"2026-03-27T15:19:51","guid":{"rendered":"https:\/\/www.uges-isere.fr\/?p=684513"},"modified":"2026-05-05T17:13:00","modified_gmt":"2026-05-05T15:13:00","slug":"un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes","status":"publish","type":"post","link":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/","title":{"rendered":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces"},"content":{"rendered":"\n<p>A l&rsquo;occasion de plusieurs d\u00e9lib\u00e9rations relatives \u00e0 la Protection de l&rsquo;enfance, les \u00e9lu.e.s du groupe UGES ont souhait\u00e9 remercier et saluer l\u2019ensemble des agents du D\u00e9partement pour leur travail de terrain dans le cadre de l\u2019aide sociale \u00e0 l\u2019enfance.<\/p>\n\n\n\n<p><strong>La protection de l\u2019enfance constitue aujourd\u2019hui un sujet majeur et particuli\u00e8rement pr\u00e9occupant \u00e0 l\u2019\u00e9chelle nationale<\/strong>. De nombreux reportages et t\u00e9moignages en d\u00e9noncent les dysfonctionnements. La D\u00e9fenseure des droits s\u2019est saisie de cette question \u00e0 travers plusieurs rapports. Le Pr\u00e9sident du D\u00e9partement de l&rsquo;Is\u00e8re a lui-m\u00eame \u00e9t\u00e9 auditionn\u00e9 \u00e0 l\u2019Assembl\u00e9e nationale dans le cadre d&rsquo;une <a href=\"https:\/\/onpe.france-enfance-protegee.fr\/rapport-sur-les-manquements-des-politiques-publiques-de-protection-de-lenfance\/\">commission d&rsquo;enqu\u00eate parlementaire.<\/a><\/p>\n\n\n\n<p>Cette actualit\u00e9, qui vient confirmer les nombreuses alertes que le groupe UGES formuler depuis cinq ans, justifiait pleinement la <strong>mise en place d\u2019une mission d\u2019information et d\u2019\u00e9valuation (MIE) sur la protection de l\u2019enfance en Is\u00e8re<\/strong> (demand\u00e9e par l&rsquo;opposition en d\u00e9cembre 2025, elle a \u00e9t\u00e9 refus\u00e9e par le Pr\u00e9sident). De telles missions ont d\u2019ailleurs \u00e9t\u00e9 engag\u00e9es dans plusieurs d\u00e9partements (Indre-et-Loire, Deux-S\u00e8vres, etc.). <\/p>\n\n\n\n<p>Si nous pouvons interroger le calendrier choisi par la majorit\u00e9 d\u00e9partementale,<strong> le groupe UGES prend acte avec satisfaction de la pr\u00e9sentation d\u2019un plan d\u2019action visant \u00e0 s\u00e9curiser le parcours des enfants confi\u00e9s au D\u00e9partement de l\u2019Is\u00e8re<\/strong>. Ces enfants doivent b\u00e9n\u00e9ficier d\u2019une protection renforc\u00e9e. il serait n\u00e9anmoins illusoire de consid\u00e9rer qu\u2019ils pourront un jour conna\u00eetre une \u00ab\u00a0enfance ordinaire\u00a0\u00bb, comme intitul\u00e9 dans un axe du plan. Tous ont en commun d\u2019avoir travers\u00e9 des \u00e9preuves et n\u00e9cessitent un accompagnement renforc\u00e9.<\/p>\n\n\n\n<p>Nous partageons ainsi le constat de leur grande vuln\u00e9rabilit\u00e9, qui peut les exposer \u00e0 des formes d\u2019exploitation. \u00c0 ce titre, l\u2019institution doit pleinement jouer son r\u00f4le de protection. Nous partageons \u00e9galement l&rsquo;engagement en faveur d\u2019une soci\u00e9t\u00e9 plus juste, plus solidaire et plus humaine.<\/p>\n\n\n\n<p><strong>Cependant, s\u2019agissant des risques d\u2019embrigadement dans les r\u00e9seaux de prostitution et de la mont\u00e9e du sexisme dans les relations entre femmes et hommes, le groupe UGES avait d\u00e9j\u00e0 alert\u00e9 \u00e0 plusieurs reprises sur ces enjeux dans cet h\u00e9micycle<\/strong>. Nous avions notamment \u00e9voqu\u00e9 les s\u00e9ances d\u2019\u00e9ducation \u00e0 la vie affective, relationnelle et sexuelle,<a href=\"https:\/\/www.uges-isere.fr\/index.php\/2025\/12\/19\/agir-pour-leducation-a-la-sexualite\/\"> en demandant un soutien exceptionnel aux Centres de sant\u00e9 sexuelle<\/a>, en particulier au Planning familial, acteur essentiel de la lutte pour l\u2019\u00e9galit\u00e9 entre les sexes. <strong>La majorit\u00e9 n\u2019a pas souhait\u00e9 renforcer ce soutien et sollicite aujourd\u2019hui davantage ces structures, notamment au b\u00e9n\u00e9fice des jeunes de l\u2019ASE. Une telle \u00e9volution peut l\u00e9gitimement interroger.<\/strong><\/p>\n\n\n\n<p>Il est \u00e9galement surprenant qu\u2019il faille attendre le d\u00e9but de l\u2019ann\u00e9e 2027 pour mettre en place une <strong>sensibilisation aux ph\u00e9nom\u00e8nes d\u2019emprise li\u00e9s \u00e0 la prostitution<\/strong>, et ce via un simple guide, alors m\u00eame que cet enjeu est prioritaire. Nous saluons dans ce sens les mesures visant \u00e0 accompagner les jeunes d\u00e9j\u00e0 victimes, telles que la plateforme d\u2019\u00e9coute ou le renforcement des consultations en psycho-traumatologie. Toutefois, <strong>nous estimons qu\u2019un effort plus important doit \u00eatre consacr\u00e9 \u00e0 la pr\u00e9vention en amont.<\/strong><\/p>\n\n\n\n<p>De m\u00eame, si la formation des professionnels au rep\u00e9rage des violences, y compris sexuelles, dans les Maisons d\u2019enfants \u00e0 caract\u00e8re social (MECS) est indispensable, il convient \u00e9galement de s\u2019interroger sur les moyens concrets allou\u00e9s \u00e0 la mise en \u0153uvre des recommandations issues de ces formations. Par ailleurs, si la cr\u00e9ation d\u2019un outil inspir\u00e9 du \u00ab\u00a0violentom\u00e8tre\u00a0\u00bb peut \u00eatre pertinente pour identifier les situations \u00e0 risque, <strong>son appellation \u00ab michtom\u00e8tre \u00bb nous semble inadapt\u00e9e, dans la mesure o\u00f9 elle tend \u00e0 culpabiliser les victimes plut\u00f4t que les auteurs ou les r\u00e9seaux.<\/strong><\/p>\n\n\n\n<p>Concernant la lutte contre la consommation de stup\u00e9fiants et l\u2019implication des jeunes dans les r\u00e9seaux de narcotrafic, les mesures annonc\u00e9es restent limit\u00e9es. Le renforcement de l\u2019information et quelques actions de sensibilisation, \u00e0 destination des jeunes et des parents, apparaissent insuffisants. Nous aurions souhait\u00e9, par exemple,<a href=\"https:\/\/www.uges-isere.fr\/index.php\/2025\/12\/19\/proteger-les-mineurs-isoles-de-lemprise-du-narcotrafic\/\"> des mesures sp\u00e9cifiques en direction des mineurs non accompagn\u00e9s (MNA), comme cela avait \u00e9t\u00e9 \u00e9voqu\u00e9 par le Pr\u00e9sident en r\u00e9ponse \u00e0 notre question orale de d\u00e9cembre.<\/a><\/p>\n\n\n\n<p>S\u2019agissant de la sant\u00e9 physique et mentale des enfants confi\u00e9s, la cr\u00e9ation d\u2019un centre m\u00e9dical sp\u00e9cialis\u00e9 nous para\u00eet pertinente. Nous soutiendrons cette initiative, notamment \u00e0 travers le CHAI. Toutefois, plusieurs enjeux essentiels demeurent insuffisamment trait\u00e9s dans ce plan d\u2019action:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qu\u2019en est-il, notamment, de l\u2019<strong>insertion professionnelle <\/strong>des jeunes issus de l\u2019aide sociale \u00e0 l\u2019enfance ? <\/li>\n\n\n\n<li>Quel accompagnement renforc\u00e9 en mati\u00e8re d\u2019orientation et d\u2019<strong>acc\u00e8s au logement <\/strong>est-il pr\u00e9vu ? Les sorties s\u00e8ches restent encore trop nombreuses en Is\u00e8re.<\/li>\n\n\n\n<li>Qu\u2019en est-il \u00e9galement des <strong>politiques de pr\u00e9vention et de soutien aux familles en amont des placements <\/strong>? Ne conviendrait-il pas de <a href=\"https:\/\/www.uges-isere.fr\/index.php\/2025\/04\/07\/donner-a-la-protection-de-lenfance-les-moyens-de-relever-ses-defis\/\">renforcer davantage la pr\u00e9vention pr\u00e9coce et l\u2019accompagnement \u00e0 la parentalit\u00e9, comme le demande r\u00e9guli\u00e8rement le groupe UGES<\/a> ?<\/li>\n\n\n\n<li>Enfin, nous ne constatons ni avanc\u00e9es significatives ni augmentation notable des moyens consacr\u00e9s \u00e0 la<strong> pr\u00e9vention sp\u00e9cialis\u00e9e ou \u00e0 la lutte contre la radicalisation.<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l&rsquo;occasion de plusieurs d\u00e9lib\u00e9rations relatives \u00e0 la Protection de l&rsquo;enfance, les \u00e9lu.e.s du groupe UGES ont souhait\u00e9 &hellip; <\/p>\n","protected":false},"author":8,"featured_media":684410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,415,414],"tags":[68,183,69,182],"class_list":["post-684513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-action-sociale","category-seance-publique-mars-2026","category-sp-2026","tag-aide-sociale-a-lenfance","tag-ase","tag-parentalite","tag-protection-de-lenfance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re\" \/>\n<meta property=\"og:description\" content=\"A l&rsquo;occasion de plusieurs d\u00e9lib\u00e9rations relatives \u00e0 la Protection de l&rsquo;enfance, les \u00e9lu.e.s du groupe UGES ont souhait\u00e9 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9partement de l&#039;Is\u00e8re\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LePrintemps38\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T15:19:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ThibaudUGES38\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GroupeUGES38\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeUGES38\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ThibaudUGES38\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/\"},\"author\":{\"name\":\"ThibaudUGES38\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#\\\/schema\\\/person\\\/a200926d67119314e8837b6a085de83a\"},\"headline\":\"Protection de l\u2019enfance : agir au-del\u00e0 des annonces\",\"datePublished\":\"2026-03-27T15:19:51+00:00\",\"dateModified\":\"2026-05-05T15:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/\"},\"wordCount\":881,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/child-9042597_1280.jpg\",\"keywords\":[\"aide sociale \u00e0 l&#039;enfance\",\"ASE\",\"parentalit\u00e9\",\"protection de l&#039;enfance\"],\"articleSection\":[\"Action sociale\",\"S\u00e9ance publique - Mars 2026\",\"SP 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/\",\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/\",\"name\":\"Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/child-9042597_1280.jpg\",\"datePublished\":\"2026-03-27T15:19:51+00:00\",\"dateModified\":\"2026-05-05T15:13:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/child-9042597_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/child-9042597_1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/2026\\\/03\\\/27\\\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.uges-isere.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection de l\u2019enfance : agir au-del\u00e0 des annonces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/\",\"name\":\"D\u00e9partement de l&#039;Is\u00e8re\",\"description\":\"Groupe d&#039;opposition UGES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uges-isere.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#organization\",\"name\":\"D\u00e9partement de l'Is\u00e8re\",\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-ok.png\",\"contentUrl\":\"https:\\\/\\\/www.uges-isere.fr\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-ok.png\",\"width\":2859,\"height\":1816,\"caption\":\"D\u00e9partement de l'Is\u00e8re\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LePrintemps38\",\"https:\\\/\\\/x.com\\\/GroupeUGES38\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uges-isere.fr\\\/#\\\/schema\\\/person\\\/a200926d67119314e8837b6a085de83a\",\"name\":\"ThibaudUGES38\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g\",\"caption\":\"ThibaudUGES38\"},\"url\":\"https:\\\/\\\/www.uges-isere.fr\\\/index.php\\\/author\\\/thibauduges38\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re","og_description":"A l&rsquo;occasion de plusieurs d\u00e9lib\u00e9rations relatives \u00e0 la Protection de l&rsquo;enfance, les \u00e9lu.e.s du groupe UGES ont souhait\u00e9 &hellip;","og_url":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/","og_site_name":"D\u00e9partement de l&#039;Is\u00e8re","article_publisher":"https:\/\/www.facebook.com\/LePrintemps38","article_published_time":"2026-03-27T15:19:51+00:00","article_modified_time":"2026-05-05T15:13:00+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg","type":"image\/jpeg"}],"author":"ThibaudUGES38","twitter_card":"summary_large_image","twitter_creator":"@GroupeUGES38","twitter_site":"@GroupeUGES38","twitter_misc":{"\u00c9crit par":"ThibaudUGES38","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#article","isPartOf":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/"},"author":{"name":"ThibaudUGES38","@id":"https:\/\/www.uges-isere.fr\/#\/schema\/person\/a200926d67119314e8837b6a085de83a"},"headline":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces","datePublished":"2026-03-27T15:19:51+00:00","dateModified":"2026-05-05T15:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/"},"wordCount":881,"commentCount":0,"publisher":{"@id":"https:\/\/www.uges-isere.fr\/#organization"},"image":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg","keywords":["aide sociale \u00e0 l&#039;enfance","ASE","parentalit\u00e9","protection de l&#039;enfance"],"articleSection":["Action sociale","S\u00e9ance publique - Mars 2026","SP 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/","url":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/","name":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces - D\u00e9partement de l&#039;Is\u00e8re","isPartOf":{"@id":"https:\/\/www.uges-isere.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#primaryimage"},"image":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg","datePublished":"2026-03-27T15:19:51+00:00","dateModified":"2026-05-05T15:13:00+00:00","breadcrumb":{"@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#primaryimage","url":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg","contentUrl":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2025\/07\/child-9042597_1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.uges-isere.fr\/index.php\/2026\/03\/27\/un-plan-pour-lenfance-mais-des-reponses-encore-insuffisantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.uges-isere.fr\/"},{"@type":"ListItem","position":2,"name":"Protection de l\u2019enfance : agir au-del\u00e0 des annonces"}]},{"@type":"WebSite","@id":"https:\/\/www.uges-isere.fr\/#website","url":"https:\/\/www.uges-isere.fr\/","name":"D\u00e9partement de l&#039;Is\u00e8re","description":"Groupe d&#039;opposition UGES","publisher":{"@id":"https:\/\/www.uges-isere.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uges-isere.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uges-isere.fr\/#organization","name":"D\u00e9partement de l'Is\u00e8re","url":"https:\/\/www.uges-isere.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uges-isere.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2021\/10\/logo-ok.png","contentUrl":"https:\/\/www.uges-isere.fr\/wp-content\/uploads\/2021\/10\/logo-ok.png","width":2859,"height":1816,"caption":"D\u00e9partement de l'Is\u00e8re"},"image":{"@id":"https:\/\/www.uges-isere.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LePrintemps38","https:\/\/x.com\/GroupeUGES38"]},{"@type":"Person","@id":"https:\/\/www.uges-isere.fr\/#\/schema\/person\/a200926d67119314e8837b6a085de83a","name":"ThibaudUGES38","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e182ebfe597e409aafe3378f828607b2b757ed94a3489b20112818296e03b151?s=96&d=mm&r=g","caption":"ThibaudUGES38"},"url":"https:\/\/www.uges-isere.fr\/index.php\/author\/thibauduges38\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/posts\/684513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/comments?post=684513"}],"version-history":[{"count":3,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/posts\/684513\/revisions"}],"predecessor-version":[{"id":684518,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/posts\/684513\/revisions\/684518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/media\/684410"}],"wp:attachment":[{"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/media?parent=684513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/categories?post=684513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uges-isere.fr\/index.php\/wp-json\/wp\/v2\/tags?post=684513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}